{"id":14070,"date":"2023-09-19T14:53:41","date_gmt":"2023-09-19T14:53:41","guid":{"rendered":"https:\/\/happieanimals.com\/?p=14070"},"modified":"2023-11-17T10:15:00","modified_gmt":"2023-11-17T10:15:00","slug":"epilepsie-bei-hunden","status":"publish","type":"post","link":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/","title":{"rendered":"Epilepsie bei Hunden"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14070\" class=\"elementor elementor-14070\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a6cb5fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a6cb5fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cdcd32c\" data-id=\"3cdcd32c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fb59f05 elementor-widget elementor-widget-image\" data-id=\"4fb59f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/elementor\/thumbs\/Hund-Epilepsie-qmjcw09iowwovr7mdk4ed8iiuzetpniq01wjphnk4o.png\" title=\"Hund Epilepsie\" alt=\"Hellbrauner Weimaraner liegt mit dem Kopf auf dem Boden im Gras\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74e61d15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74e61d15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-104a2d52\" data-id=\"104a2d52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7675cac3 elementor-widget elementor-widget-spacer\" data-id=\"7675cac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b2d363 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"73b2d363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Epilepsie bei Hunden<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ecf93f3 elementor-widget elementor-widget-text-editor\" data-id=\"3ecf93f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Epilepsie ist eine der h\u00e4ufigsten neurologischen Erkrankungen bei Hunden. In diesem Blog haben wir dir alles zu den Ursachen, Symptomen und zur Behandlung der Erkrankung zusammengefasst.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d08c9bf elementor-widget elementor-widget-table-of-contents\" data-id=\"d08c9bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;no_headings_message&quot;:&quot;Es wurden keine \\u00dcberschriften auf dieser Seite gefunden.&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tWas du \u00fcber Epilepsie beim Hund wissen solltest:\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__d08c9bf\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eb7bb60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eb7bb60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13268248\" data-id=\"13268248\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68d4f03f elementor-widget elementor-widget-heading\" data-id=\"68d4f03f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Was ist Epilepsie bei Hunden?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-030f0c0 elementor-widget elementor-widget-text-editor\" data-id=\"030f0c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Epilepsie ist eine neurologische Erkrankung, bei der es zu einer vor\u00fcbergehenden Funktionsst\u00f6rungen des Gehirns kommt. Von der sogenannten `Fallsucht` k\u00f6nnen auch Hunde und andere Tiere betroffen sein. Die Krankheit ist durch wiederkehrende Anf\u00e4lle gekennzeichnet, die durch abnormale elektrische Aktivit\u00e4t im Gehirn ausgel\u00f6st werden. Dabei k\u00f6nnen Hunde jeden Alters, jeder Rasse und jeder Gr\u00f6\u00dfe unter diesen Anf\u00e4llen leiden, obwohl einige Hunderassen anf\u00e4lliger f\u00fcr Epilepsie sind als andere, was auf eine genetische Veranlagung hinweist. <\/span><span style=\"font-weight: 400;\">Es ist wichtig zu beachten, dass Epilepsie eine behandelbare Erkrankung ist, und mit der richtigen Betreuung und medizinischen Versorgung k\u00f6nnen Hunde mit Epilepsie ein gl\u00fcckliches und erf\u00fclltes Leben f\u00fchren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64a176d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64a176d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44f2d1a4\" data-id=\"44f2d1a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e6bbd1 elementor-widget elementor-widget-heading\" data-id=\"3e6bbd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Ursachen von Epilepsie bei Hunden\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-146d3661 elementor-widget elementor-widget-text-editor\" data-id=\"146d3661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Die genauen Ursachen von Epilepsie bei Hunden sind nicht immer bekannt. Es gibt jedoch verschiedene Faktoren, die zu epileptischen Anf\u00e4llen f\u00fchren k\u00f6nnen. Bei manchen Hunden kann die Epilepsie genetisch bedingt sein. <\/span><span style=\"font-weight: 400;\">Es wird auch vermutet, dass sowohl genetische als auch Umweltfaktoren eine Rolle spielen k\u00f6nnen. Andere m\u00f6gliche Ausl\u00f6ser f\u00fcr Anf\u00e4lle sind Hirntumore, Vergiftungen, Sch\u00e4delverletzungen, <\/span><span style=\"font-weight: 400;\">Infektionen oder Stoffwechselst\u00f6rungen.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">In einigen F\u00e4llen kann die Epilepsie auch idiopathisch sein, was bedeutet, dass keine spezifische Ursache gefunden werden kann. Es ist wichtig, dass Tier\u00e4rzte eine gr\u00fcndliche Untersuchung durchf\u00fchren, um die m\u00f6glichen Ursachen der Epilepsie bei einem Hund zu ermitteln.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74e4a56c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74e4a56c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b583934\" data-id=\"1b583934\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37f5865a elementor-widget elementor-widget-heading\" data-id=\"37f5865a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Symptome von Epilepsie bei Hunden\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bfd3a6f elementor-widget elementor-widget-text-editor\" data-id=\"2bfd3a6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Die Symptome von Epilepsie k\u00f6nnen von Hund zu Hund variieren. Ein typisches Anzeichen f\u00fcr einen epileptischen Anfall ist ein pl\u00f6tzlicher Verlust der K\u00f6rperkontrolle. Der Hund kann zucken, krampfen, sich hinlegen und dabei Urin oder Kot verlieren. Ein Anfall kann nur wenige Sekunden oder sogar mehrere Minuten dauern. Nach einem dieser Anf\u00e4lle kann es vorkommen, dass der Hund vor\u00fcbergehend desorientiert oder benommen ist. Der Hund kann vor einem Anfall auch unruhig sein, nerv\u00f6s wirken, jammern, zittern oder vermehrt Speichel produzieren.<\/span><\/p><p><span style=\"font-weight: 400;\">Bei einer sekund\u00e4ren oder symptomatischen Epilepsie tritt die Erkrankung als Folge einer anderen Grunderkrankung auf. Dabei kann es sein, dass bereits eine Hirnsch\u00e4digung oder Erkrankung vorliegt, die sich unter anderem in Form von epileptischen Anf\u00e4llen \u00e4u\u00dfert.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-690ea8b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"690ea8b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b9e291a\" data-id=\"3b9e291a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45fd3535 elementor-widget elementor-widget-heading\" data-id=\"45fd3535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Diagnose von Epilepsie bei Hunden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14a9fde8 elementor-widget elementor-widget-text-editor\" data-id=\"14a9fde8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Wenn du vermutest, dass dein Hund an Epilepsie leidet, oder er sich anders als sonst verh\u00e4lt, ist es wichtig, ihn von deinem Tierarzt oder deiner Tier\u00e4rztin untersuchen zu lassen. Dann werden gr\u00fcndliche Untersuchungen durchgef\u00fchrt und m\u00f6glicherweise weitere diagnostische Tests wie Blutuntersuchungen oder eine MRT-Untersuchung des Gehirns gemacht. Wenn dein Hund betroffen ist oder die Vermutung einer Erkrankung im Raum steht, kannst du<\/span><span style=\"font-weight: 400;\"> die Symptome deines Hundes beobachten und gegebenenfalls ein Symptomtagebuch f\u00fchren. Darin h\u00e4ltst du zum Beispiel fest, wie oft bestimmte Symptome auftreten oder wie lange Anf\u00e4lle anhalten. So kann eine ausf\u00fchrliche Anamnese durchgef\u00fchrt werden. <\/span><span style=\"font-weight: 400;\">Eine genaue Diagnose ist entscheidend, um die bestm\u00f6gliche Behandlung f\u00fcr deinen Hund festzulegen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b54f4d7 elementor-widget elementor-widget-heading\" data-id=\"b54f4d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Behandlung von Epilepsie bei Hunden\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1e588c elementor-widget elementor-widget-text-editor\" data-id=\"b1e588c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Die Behandlung von Epilepsie bei Hunden zielt darauf ab, die Anzahl und Schwere der Anf\u00e4lle zu reduzieren. In den meisten F\u00e4llen werden Antikonvulsiva verschrieben, um die elektrische Aktivit\u00e4t im Gehirn zu kontrollieren. Die Dosierung und das Medikament werden individuell auf den Hund abgestimmt. Dabei ist es wichtig, die verschriebenen Medikamente regelm\u00e4\u00dfig einzugeben und die Fortschritte zu \u00fcberwachen.<\/span><\/p><p>\u00a0<\/p><p><b>Tipps f\u00fcr Hundebesitzer mit einem epileptischen Hund<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Informiere dich \u00fcber Epilepsie und die spezifischen Bed\u00fcrfnisse deines Hundes<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Halte deinen Hund von potenziellen Ausl\u00f6sern fern, wie Stress oder bestimmten Lebensmitteln<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Achte auf regelm\u00e4\u00dfige Tierarztbesuche und halte die Behandlung deines Hundes auf dem neuesten Stand<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">F\u00fchre Tagebuch \u00fcber die Anf\u00e4lle deines Hundes, um m\u00f6gliche Muster zu erkennen.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Schaffe eine sichere Umgebung f\u00fcr deinen Hund, um Verletzungen w\u00e4hrend eines Anfalls zu vermeiden<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-576cd76 elementor-widget elementor-widget-heading\" data-id=\"576cd76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Zusammenfassung\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0df4791 elementor-widget elementor-widget-text-editor\" data-id=\"0df4791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Epilepsie bei Hunden ist eine ernsthafte Erkrankung, die von den Hundebesitzern eine sorgf\u00e4ltige Aufmerksamkeit erfordert. Sollten Symptome auftreten, ist es wichtig, so fr\u00fch wie m\u00f6glich zu Tier\u00e4rzten zu gehen, damit diese eine genaue Diagnose stellen und eine angemessene Behandlung beginnen k\u00f6nnen. Mit der richtigen Pflege und Medikation k\u00f6nnen Hunde mit Epilepsie ein langes Leben f\u00fchren.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Wenn du weitere Fragen zur Epilepsie bei Hunden oder zur Pflege eines Hundes mit dieser Erkrankung hast, z\u00f6gere nicht, deinen Tierarzt zu konsultieren.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6ee5d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6ee5d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45fc1186\" data-id=\"45fc1186\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-225d75f2 elementor-widget elementor-widget-image\" data-id=\"225d75f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/app.horseanalytics.com\/Happie\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"111\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/badges-together-delete-after-01-600x111.png\" class=\"attachment-woocommerce_single size-woocommerce_single wp-image-13016\" alt=\"\" srcset=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/badges-together-delete-after-01-600x111.png 600w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/badges-together-delete-after-01-300x56.png 300w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/badges-together-delete-after-01-1024x190.png 1024w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/badges-together-delete-after-01-768x143.png 768w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/badges-together-delete-after-01-1536x285.png 1536w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/badges-together-delete-after-01.png 1913w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a3a3d6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a3a3d6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66fd7bf6\" data-id=\"66fd7bf6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16aeb851 elementor-widget elementor-widget-heading\" data-id=\"16aeb851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Verwandte Artikel<\/h3>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41ea6de8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41ea6de8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-683c9341\" data-id=\"683c9341\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21e36a56 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"21e36a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-16921 post type-post status-publish format-standard has-post-thumbnail hentry category-alles-rund-um-dem-hund category-hundegesundheit\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/happieanimals.com\/de\/darmerkrankungen-bei-hunden\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/11\/Darmerkrankungen-bei-Hunden-300x150.png\" class=\"attachment-medium size-medium wp-image-16924\" alt=\"Ein Beagle liegt in seinem K\u00f6rbchen\" srcset=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/11\/Darmerkrankungen-bei-Hunden-300x150.png 300w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/11\/Darmerkrankungen-bei-Hunden-1024x512.png 1024w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/11\/Darmerkrankungen-bei-Hunden-768x384.png 768w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/11\/Darmerkrankungen-bei-Hunden-1536x768.png 1536w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/11\/Darmerkrankungen-bei-Hunden-600x300.png 600w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/11\/Darmerkrankungen-bei-Hunden.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/happieanimals.com\/de\/darmerkrankungen-bei-hunden\/\" >\n\t\t\t\tDarmerkrankungen bei Hunden\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Selbst f\u00fcr die st\u00e4rksten Hundebesitzer kann es eine stressige Erfahrung sein, wenn der geliebte Vierbeiner<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/happieanimals.com\/de\/darmerkrankungen-bei-hunden\/\" aria-label=\"Mehr \u00fcber Darmerkrankungen bei Hunden\" tabindex=\"-1\" >\n\t\t\tJetzt lesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14838 post type-post status-publish format-standard has-post-thumbnail hentry category-alles-rund-um-dem-hund category-hundegesundheit category-unkategorisiert\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/happieanimals.com\/de\/anaplasmose-beim-hund\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/10\/Anaplasmose-beim-Hund-300x150.png\" class=\"attachment-medium size-medium wp-image-14841\" alt=\"Wolfspitz sitzt im Wald\" srcset=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/10\/Anaplasmose-beim-Hund-300x150.png 300w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/10\/Anaplasmose-beim-Hund-1024x512.png 1024w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/10\/Anaplasmose-beim-Hund-768x384.png 768w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/10\/Anaplasmose-beim-Hund-1536x768.png 1536w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/10\/Anaplasmose-beim-Hund-600x300.png 600w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/10\/Anaplasmose-beim-Hund.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/happieanimals.com\/de\/anaplasmose-beim-hund\/\" >\n\t\t\t\tAnaplasmose beim Hund\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Wenn du dich um die Gesundheit deines pelzigen Begleiters sorgst, dann ist es wichtig, gut<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/happieanimals.com\/de\/anaplasmose-beim-hund\/\" aria-label=\"Mehr \u00fcber Anaplasmose beim Hund\" tabindex=\"-1\" >\n\t\t\tJetzt lesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-13611 post type-post status-publish format-standard has-post-thumbnail hentry category-alles-rund-um-dem-hund category-hundegesundheit category-unkategorisiert\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/happieanimals.com\/de\/grannen-beim-hund-gefahr-im-sommer\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Grannen-1-300x150.png\" class=\"attachment-medium size-medium wp-image-13619\" alt=\"schwarzer Hund rennt im Feld\" srcset=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Grannen-1-300x150.png 300w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Grannen-1-1024x512.png 1024w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Grannen-1-768x384.png 768w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Grannen-1-1536x768.png 1536w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Grannen-1-600x300.png 600w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Grannen-1.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/happieanimals.com\/de\/grannen-beim-hund-gefahr-im-sommer\/\" >\n\t\t\t\tGrannen beim Hund &#8211; Gefahr im Sommer\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Was sind Grannen und warum k\u00f6nnen sie f\u00fcr deinen Hund gef\u00e4hrlich sein? Alles \u00fcber die<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/happieanimals.com\/de\/grannen-beim-hund-gefahr-im-sommer\/\" aria-label=\"Mehr \u00fcber Grannen beim Hund &#8211; Gefahr im Sommer\" tabindex=\"-1\" >\n\t\t\tJetzt lesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20398 post type-post status-publish format-standard has-post-thumbnail hentry category-alles-rund-um-dem-hund category-hundegesundheit\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/happieanimals.com\/de\/atherome\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Atherome-300x150.png\" class=\"attachment-medium size-medium wp-image-20400\" alt=\"\" srcset=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Atherome-300x150.png 300w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Atherome-1024x512.png 1024w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Atherome-768x384.png 768w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Atherome-1536x768.png 1536w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Atherome-600x300.png 600w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Atherome.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/happieanimals.com\/de\/atherome\/\" >\n\t\t\t\tAtherome\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Herzlich willkommen bei Happie Dog! In unserem heutigen Blogartikel widmen wir uns einem Thema, das<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/happieanimals.com\/de\/atherome\/\" aria-label=\"Mehr \u00fcber Atherome\" tabindex=\"-1\" >\n\t\t\tJetzt lesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-14226 post type-post status-publish format-standard has-post-thumbnail hentry category-alles-rund-um-dem-hund category-hundegesundheit\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/happieanimals.com\/de\/blasensteine-bei-hunden\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Blasensteine-300x150.png\" class=\"attachment-medium size-medium wp-image-14230\" alt=\"Kleiner schwarz-wei\u00dfer Hund steht auf einer Wiese und hechelt\" srcset=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Blasensteine-300x150.png 300w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Blasensteine-1024x512.png 1024w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Blasensteine-768x384.png 768w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Blasensteine-1536x768.png 1536w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Blasensteine-600x300.png 600w, https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Blasensteine.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/happieanimals.com\/de\/blasensteine-bei-hunden\/\" >\n\t\t\t\tBlasensteine bei Hunden\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Als Hundebesitzer m\u00f6chtest du sicherstellen, dass dein Vierbeiner gl\u00fccklich und gesund ist. Leider k\u00f6nnen Blasensteine<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/happieanimals.com\/de\/blasensteine-bei-hunden\/\" aria-label=\"Mehr \u00fcber Blasensteine bei Hunden\" tabindex=\"-1\" >\n\t\t\tJetzt lesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20337 post type-post status-publish format-standard has-post-thumbnail hentry category-alles-rund-um-dem-hund category-hundegesundheit\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/happieanimals.com\/de\/morbus-addison\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Morbus-Addison-300x150.png\" class=\"attachment-medium size-medium wp-image-20339\" alt=\"\" srcset=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Morbus-Addison-300x150.png 300w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Morbus-Addison-1024x512.png 1024w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Morbus-Addison-768x384.png 768w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Morbus-Addison-1536x768.png 1536w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Morbus-Addison-600x300.png 600w, https:\/\/happieanimals.com\/wp-content\/uploads\/2024\/01\/Morbus-Addison.png 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/happieanimals.com\/de\/morbus-addison\/\" >\n\t\t\t\tMorbus Addison\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Herzlich willkommen beim Happie Dog \u2013 deiner Anlaufstelle f\u00fcr alles rund um die Gesundheit und<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/happieanimals.com\/de\/morbus-addison\/\" aria-label=\"Mehr \u00fcber Morbus Addison\" tabindex=\"-1\" >\n\t\t\tJetzt lesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Epilepsie ist eine der h\u00e4ufigsten neurologischen Erkrankungen bei Hunden. In diesem Blog haben wir dir alles zu den Ursachen, Symptomen und zur Behandlung der Erkrankung zusammengefasst. Was du \u00fcber Epilepsie beim Hund wissen solltest: Was ist Epilepsie bei Hunden? Epilepsie ist eine neurologische Erkrankung, bei der es zu einer vor\u00fcbergehenden Funktionsst\u00f6rungen des Gehirns kommt. Von [&hellip;]<\/p>\n","protected":false},"author":2360,"featured_media":14073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[229,230,50],"tags":[],"class_list":["post-14070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alles-rund-um-dem-hund","category-hundegesundheit","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Epilepsie bei Hunden<\/title>\n<meta name=\"description\" content=\"Hier findest du Informationen \u00fcber Epilepsie und deren Ursachen. Erfahre wie sich die Krankheit \u00e4u\u00dfert und welche Ma\u00dfnahmen du ergreifen kannst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Epilepsie bei Hunden\" \/>\n<meta property=\"og:description\" content=\"Hier findest du Informationen \u00fcber Epilepsie und deren Ursachen. Erfahre wie sich die Krankheit \u00e4u\u00dfert und welche Ma\u00dfnahmen du ergreifen kannst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/\" \/>\n<meta property=\"og:site_name\" content=\"Happie Horse Management App\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-19T14:53:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T10:15:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie-1024x512.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Franzi Schommertz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Franzi Schommertz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/\"},\"author\":{\"name\":\"Franzi Schommertz\",\"@id\":\"https:\/\/happieanimals.com\/de\/#\/schema\/person\/1a7fc61b7571aa08d464bf1cad8bfd90\"},\"headline\":\"Epilepsie bei Hunden\",\"datePublished\":\"2023-09-19T14:53:41+00:00\",\"dateModified\":\"2023-11-17T10:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/\"},\"wordCount\":765,\"publisher\":{\"@id\":\"https:\/\/happieanimals.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png\",\"articleSection\":[\"Alles rund um dem Hund\",\"Hundegesundheit\",\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/\",\"url\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/\",\"name\":\"Epilepsie bei Hunden\",\"isPartOf\":{\"@id\":\"https:\/\/happieanimals.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png\",\"datePublished\":\"2023-09-19T14:53:41+00:00\",\"dateModified\":\"2023-11-17T10:15:00+00:00\",\"description\":\"Hier findest du Informationen \u00fcber Epilepsie und deren Ursachen. Erfahre wie sich die Krankheit \u00e4u\u00dfert und welche Ma\u00dfnahmen du ergreifen kannst.\",\"breadcrumb\":{\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage\",\"url\":\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png\",\"contentUrl\":\"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png\",\"width\":2000,\"height\":1000,\"caption\":\"Hellbrauner Weimaraner liegt mit dem Kopf auf dem Boden im Gras\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/happieanimals.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Epilepsie bei Hunden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/happieanimals.com\/de\/#website\",\"url\":\"https:\/\/happieanimals.com\/de\/\",\"name\":\"Happie Horse App\",\"description\":\"Let\u00b4s create a more happie world for horses, pets and people\",\"publisher\":{\"@id\":\"https:\/\/happieanimals.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/happieanimals.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/happieanimals.com\/de\/#organization\",\"name\":\"Happie Horse App\",\"url\":\"https:\/\/happieanimals.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/happieanimals.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/happieanimals.com\/wp-content\/uploads\/2026\/08\/cropped-logo-gold_2.webp\",\"contentUrl\":\"https:\/\/happieanimals.com\/wp-content\/uploads\/2026\/08\/cropped-logo-gold_2.webp\",\"width\":1537,\"height\":395,\"caption\":\"Happie Horse App\"},\"image\":{\"@id\":\"https:\/\/happieanimals.com\/de\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/happieanimals.com\/de\/#\/schema\/person\/1a7fc61b7571aa08d464bf1cad8bfd90\",\"name\":\"Franzi Schommertz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/happieanimals.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/70384d756d599ceffe583af89d51596d2e497bc39e6921858657639ab9776fe4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/70384d756d599ceffe583af89d51596d2e497bc39e6921858657639ab9776fe4?s=96&d=mm&r=g\",\"caption\":\"Franzi Schommertz\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Epilepsie bei Hunden","description":"Hier findest du Informationen \u00fcber Epilepsie und deren Ursachen. Erfahre wie sich die Krankheit \u00e4u\u00dfert und welche Ma\u00dfnahmen du ergreifen kannst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/","og_locale":"de_DE","og_type":"article","og_title":"Epilepsie bei Hunden","og_description":"Hier findest du Informationen \u00fcber Epilepsie und deren Ursachen. Erfahre wie sich die Krankheit \u00e4u\u00dfert und welche Ma\u00dfnahmen du ergreifen kannst.","og_url":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/","og_site_name":"Happie Horse Management App","article_published_time":"2023-09-19T14:53:41+00:00","article_modified_time":"2023-11-17T10:15:00+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie-1024x512.png","type":"image\/png"}],"author":"Franzi Schommertz","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Franzi Schommertz"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#article","isPartOf":{"@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/"},"author":{"name":"Franzi Schommertz","@id":"https:\/\/happieanimals.com\/de\/#\/schema\/person\/1a7fc61b7571aa08d464bf1cad8bfd90"},"headline":"Epilepsie bei Hunden","datePublished":"2023-09-19T14:53:41+00:00","dateModified":"2023-11-17T10:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/"},"wordCount":765,"publisher":{"@id":"https:\/\/happieanimals.com\/de\/#organization"},"image":{"@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage"},"thumbnailUrl":"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png","articleSection":["Alles rund um dem Hund","Hundegesundheit","Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/","url":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/","name":"Epilepsie bei Hunden","isPartOf":{"@id":"https:\/\/happieanimals.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage"},"image":{"@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage"},"thumbnailUrl":"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png","datePublished":"2023-09-19T14:53:41+00:00","dateModified":"2023-11-17T10:15:00+00:00","description":"Hier findest du Informationen \u00fcber Epilepsie und deren Ursachen. Erfahre wie sich die Krankheit \u00e4u\u00dfert und welche Ma\u00dfnahmen du ergreifen kannst.","breadcrumb":{"@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#primaryimage","url":"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png","contentUrl":"https:\/\/happieanimals.com\/wp-content\/uploads\/2023\/09\/Hund-Epilepsie.png","width":2000,"height":1000,"caption":"Hellbrauner Weimaraner liegt mit dem Kopf auf dem Boden im Gras"},{"@type":"BreadcrumbList","@id":"https:\/\/happieanimals.com\/de\/epilepsie-bei-hunden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/happieanimals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Epilepsie bei Hunden"}]},{"@type":"WebSite","@id":"https:\/\/happieanimals.com\/de\/#website","url":"https:\/\/happieanimals.com\/de\/","name":"Happie Horse App","description":"Let\u00b4s create a more happie world for horses, pets and people","publisher":{"@id":"https:\/\/happieanimals.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/happieanimals.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/happieanimals.com\/de\/#organization","name":"Happie Horse App","url":"https:\/\/happieanimals.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/happieanimals.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/happieanimals.com\/wp-content\/uploads\/2026\/08\/cropped-logo-gold_2.webp","contentUrl":"https:\/\/happieanimals.com\/wp-content\/uploads\/2026\/08\/cropped-logo-gold_2.webp","width":1537,"height":395,"caption":"Happie Horse App"},"image":{"@id":"https:\/\/happieanimals.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/happieanimals.com\/de\/#\/schema\/person\/1a7fc61b7571aa08d464bf1cad8bfd90","name":"Franzi Schommertz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/happieanimals.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/70384d756d599ceffe583af89d51596d2e497bc39e6921858657639ab9776fe4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/70384d756d599ceffe583af89d51596d2e497bc39e6921858657639ab9776fe4?s=96&d=mm&r=g","caption":"Franzi Schommertz"}}]}},"_links":{"self":[{"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/posts\/14070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/users\/2360"}],"replies":[{"embeddable":true,"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/comments?post=14070"}],"version-history":[{"count":14,"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/posts\/14070\/revisions"}],"predecessor-version":[{"id":17398,"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/posts\/14070\/revisions\/17398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/media\/14073"}],"wp:attachment":[{"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/media?parent=14070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/categories?post=14070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/happieanimals.com\/de\/wp-json\/wp\/v2\/tags?post=14070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}